{"id":36849,"date":"2026-07-01T22:01:39","date_gmt":"2026-07-01T22:01:39","guid":{"rendered":"https:\/\/ominiahome.com\/product\/roberto-cavalli-jaguar-dinner-plate\/"},"modified":"2026-07-01T22:01:39","modified_gmt":"2026-07-01T22:01:39","slug":"roberto-cavalli-jaguar-dinner-plate","status":"publish","type":"product","link":"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/","title":{"rendered":"Roberto Cavalli JAGUAR Dinner Plate"},"content":{"rendered":"<p>A dinner plate from Roberto Cavalli&#8217;s JAGUAR collection designed for elegant dining with signature motifs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dinner plate from JAGUAR collection.<\/p>\n","protected":false},"featured_media":36850,"comment_status":"open","ping_status":"closed","template":"","meta":{"nf_dc_page":""},"product_brand":[],"product_cat":[1203],"product_tag":[1244,1204,1234],"class_list":["post-36849","product","type-product","status-publish","has-post-thumbnail","product_cat-dining","product_tag-jaguar","product_tag-plate","product_tag-roberto-cavalli","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Roberto Cavalli JAGUAR Dinner Plate - Ominia Home<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roberto Cavalli JAGUAR Dinner Plate\" \/>\n<meta property=\"og:description\" content=\"Dinner plate from JAGUAR collection.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/\" \/>\n<meta property=\"og:site_name\" content=\"Ominia Home\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ominiahome.com\/wp-content\/uploads\/2026\/04\/favicon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0627\u0644\u0633\u0639\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"25&nbsp;OMR\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0627\u0644\u062a\u0648\u0641\u0631\" \/>\n\t<meta name=\"twitter:data2\" content=\"\u0645\u062a\u0648\u0641\u0631 \u0641\u064a \u0627\u0644\u0645\u062e\u0632\u0648\u0646\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/ominiahome.com\\\/ar\\\/product\\\/roberto-cavalli-jaguar-dinner-plate\\\/\",\"url\":\"http:\\\/\\\/ominiahome.com\\\/ar\\\/product\\\/roberto-cavalli-jaguar-dinner-plate\\\/\",\"name\":\"Roberto Cavalli JAGUAR Dinner Plate - Ominia Home\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ominiahome.com\\\/ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/ominiahome.com\\\/ar\\\/product\\\/roberto-cavalli-jaguar-dinner-plate\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/ominiahome.com\\\/ar\\\/product\\\/roberto-cavalli-jaguar-dinner-plate\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/ominiahome.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/roberto-cavalli-jaguar-set-6-dinner-plate-275-cm.jpg\",\"datePublished\":\"2026-07-01T22:01:39+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/ominiahome.com\\\/ar\\\/product\\\/roberto-cavalli-jaguar-dinner-plate\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/ominiahome.com\\\/ar\\\/product\\\/roberto-cavalli-jaguar-dinner-plate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"http:\\\/\\\/ominiahome.com\\\/ar\\\/product\\\/roberto-cavalli-jaguar-dinner-plate\\\/#primaryimage\",\"url\":\"http:\\\/\\\/ominiahome.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/roberto-cavalli-jaguar-set-6-dinner-plate-275-cm.jpg\",\"contentUrl\":\"http:\\\/\\\/ominiahome.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/roberto-cavalli-jaguar-set-6-dinner-plate-275-cm.jpg\",\"width\":1300,\"height\":1300},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/ominiahome.com\\\/ar\\\/product\\\/roberto-cavalli-jaguar-dinner-plate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ominiahome.com\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0644\u0645\u062a\u062c\u0631\",\"item\":\"https:\\\/\\\/ominiahome.com\\\/ar\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Roberto Cavalli JAGUAR Dinner Plate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ominiahome.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/ominiahome.com\\\/ar\\\/\",\"name\":\"Ominia Home\",\"description\":\"The Art of Luxury Living &amp; Designer Home D\u00e9cor\",\"publisher\":{\"@id\":\"https:\\\/\\\/ominiahome.com\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ominiahome.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/ominiahome.com\\\/ar\\\/#organization\",\"name\":\"Ominia Home\",\"url\":\"https:\\\/\\\/ominiahome.com\\\/ar\\\/\",\"logo\":{\"@id\":\"http:\\\/\\\/ominiahome.com\\\/ar\\\/product\\\/roberto-cavalli-jaguar-dinner-plate\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"http:\\\/\\\/ominiahome.com\\\/ar\\\/product\\\/roberto-cavalli-jaguar-dinner-plate\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ominia.home\\\/\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Saturday\",\"Sunday\",\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"http:\\\/\\\/ominiahome.com\\\/ar\\\/product\\\/roberto-cavalli-jaguar-dinner-plate\\\/#local-main-organization-logo\",\"url\":\"http:\\\/\\\/ominiahome.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-06-at-2.06.06-PM.jpeg\",\"contentUrl\":\"http:\\\/\\\/ominiahome.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-04-06-at-2.06.06-PM.jpeg\",\"width\":1020,\"height\":1021,\"caption\":\"Ominia Home\"}]}<\/script>\n<meta property=\"product:price:amount\" content=\"25\" \/>\n<meta property=\"product:price:currency\" content=\"OMR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"8059037100360\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Roberto Cavalli JAGUAR Dinner Plate - Ominia Home","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/","og_locale":"ar_AR","og_type":"article","og_title":"Roberto Cavalli JAGUAR Dinner Plate","og_description":"Dinner plate from JAGUAR collection.","og_url":"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/","og_site_name":"Ominia Home","og_image":[{"width":512,"height":512,"url":"http:\/\/ominiahome.com\/wp-content\/uploads\/2026\/04\/favicon.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"\u0627\u0644\u0633\u0639\u0631":"25&nbsp;OMR","\u0627\u0644\u062a\u0648\u0641\u0631":"\u0645\u062a\u0648\u0641\u0631 \u0641\u064a \u0627\u0644\u0645\u062e\u0632\u0648\u0646"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/","url":"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/","name":"Roberto Cavalli JAGUAR Dinner Plate - Ominia Home","isPartOf":{"@id":"https:\/\/ominiahome.com\/ar\/#website"},"primaryImageOfPage":{"@id":"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/#primaryimage"},"image":{"@id":"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/#primaryimage"},"thumbnailUrl":"http:\/\/ominiahome.com\/wp-content\/uploads\/2026\/07\/roberto-cavalli-jaguar-set-6-dinner-plate-275-cm.jpg","datePublished":"2026-07-01T22:01:39+00:00","breadcrumb":{"@id":"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/#primaryimage","url":"http:\/\/ominiahome.com\/wp-content\/uploads\/2026\/07\/roberto-cavalli-jaguar-set-6-dinner-plate-275-cm.jpg","contentUrl":"http:\/\/ominiahome.com\/wp-content\/uploads\/2026\/07\/roberto-cavalli-jaguar-set-6-dinner-plate-275-cm.jpg","width":1300,"height":1300},{"@type":"BreadcrumbList","@id":"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ominiahome.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u0645\u062a\u062c\u0631","item":"https:\/\/ominiahome.com\/ar\/shop\/"},{"@type":"ListItem","position":3,"name":"Roberto Cavalli JAGUAR Dinner Plate"}]},{"@type":"WebSite","@id":"https:\/\/ominiahome.com\/ar\/#website","url":"https:\/\/ominiahome.com\/ar\/","name":"Ominia Home","description":"The Art of Luxury Living &amp; Designer Home D\u00e9cor","publisher":{"@id":"https:\/\/ominiahome.com\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ominiahome.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":["Organization","Place"],"@id":"https:\/\/ominiahome.com\/ar\/#organization","name":"Ominia Home","url":"https:\/\/ominiahome.com\/ar\/","logo":{"@id":"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/#local-main-organization-logo"},"image":{"@id":"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/#local-main-organization-logo"},"sameAs":["https:\/\/www.instagram.com\/ominia.home\/"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Saturday","Sunday","Monday","Tuesday","Wednesday","Thursday","Friday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"ar","@id":"http:\/\/ominiahome.com\/ar\/product\/roberto-cavalli-jaguar-dinner-plate\/#local-main-organization-logo","url":"http:\/\/ominiahome.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-06-at-2.06.06-PM.jpeg","contentUrl":"http:\/\/ominiahome.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-04-06-at-2.06.06-PM.jpeg","width":1020,"height":1021,"caption":"Ominia Home"}]},"product_price_amount":"25","product_price_currency":"OMR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"8059037100360","product_condition":"new"},"_links":{"self":[{"href":"http:\/\/ominiahome.com\/ar\/wp-json\/wp\/v2\/product\/36849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ominiahome.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/ominiahome.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"http:\/\/ominiahome.com\/ar\/wp-json\/wp\/v2\/comments?post=36849"}],"version-history":[{"count":0,"href":"http:\/\/ominiahome.com\/ar\/wp-json\/wp\/v2\/product\/36849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ominiahome.com\/ar\/wp-json\/wp\/v2\/media\/36850"}],"wp:attachment":[{"href":"http:\/\/ominiahome.com\/ar\/wp-json\/wp\/v2\/media?parent=36849"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"http:\/\/ominiahome.com\/ar\/wp-json\/wp\/v2\/product_brand?post=36849"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/ominiahome.com\/ar\/wp-json\/wp\/v2\/product_cat?post=36849"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/ominiahome.com\/ar\/wp-json\/wp\/v2\/product_tag?post=36849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}